{"id":5320,"date":"2024-12-13T17:54:29","date_gmt":"2024-12-13T16:54:29","guid":{"rendered":"https:\/\/angelomusa.com\/?post_type=product&#038;p=5320"},"modified":"2025-10-24T11:32:01","modified_gmt":"2025-10-24T09:32:01","slug":"classique","status":"publish","type":"product","link":"https:\/\/angelomusa.com\/en\/product\/classique\/","title":{"rendered":"Coffret Confiture Classique"},"content":{"rendered":"<p>Composez votre bo\u00eete id\u00e9ale avec <strong>trois pots de confitures au choix<\/strong>. Parfaite pour <strong>offrir<\/strong> ou se faire plaisir, elle allie \u00e9l\u00e9gance et gourmandise, mettant en lumi\u00e8re le savoir-faire artisanal de <strong>La Confiture Angelo Musa.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p><strong>Offrez ou faites-vous plaisir avec nos \u00e9l\u00e9gantes bo\u00eetes \u00e0 confiture<\/strong>s, con\u00e7ues pour sublimer l\u2019art de la gourmandise. Chaque bo\u00eete peut accueillir t<strong>rois pots de confitures de votre choix<\/strong>, pour cr\u00e9er une s\u00e9lection sur-mesure adapt\u00e9e \u00e0 vos envies ou celles de vos proches.<\/p>\n<p>Parfaites pour un<strong> cadeau raffin\u00e9<\/strong> ou pour enrichir votre propre collection, ces bo\u00eetes allient praticit\u00e9 et esth\u00e9tisme, mettant en valeur le savoir-faire artisanal de La <strong>Confiture Angelo Musa.<\/strong><\/p>","protected":false},"featured_media":5328,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[48],"product_tag":[],"class_list":{"0":"post-5320","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-coffret-angelo-musa","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coffret Confiture Classique - Angelo Musa<\/title>\n<meta name=\"description\" content=\"Composez votre bo\u00eete id\u00e9ale avec trois pots de confitures au choix. Parfaite pour offrir ou se faire plaisir, elle allie \u00e9l\u00e9gance et gourmandise, mettant en lumi\u00e8re le savoir-faire artisanal de La Confiture Angelo Musa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angelomusa.com\/en\/product\/classique\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coffret Confiture Classique - Angelo Musa\" \/>\n<meta property=\"og:description\" content=\"Composez votre bo\u00eete id\u00e9ale avec trois pots de confitures au choix. Parfaite pour offrir ou se faire plaisir, elle allie \u00e9l\u00e9gance et gourmandise, mettant en lumi\u00e8re le savoir-faire artisanal de La Confiture Angelo Musa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angelomusa.com\/en\/product\/classique\/\" \/>\n<meta property=\"og:site_name\" content=\"Angelo Musa\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-24T09:32:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/angelomusa.com\/wp-content\/uploads\/2024\/12\/IMG_7779-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angelomusa.com\\\/produit\\\/classique\\\/\",\"url\":\"https:\\\/\\\/angelomusa.com\\\/produit\\\/classique\\\/\",\"name\":\"Coffret Confiture Classique - Angelo Musa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.angelomusa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/angelomusa.com\\\/produit\\\/classique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/angelomusa.com\\\/produit\\\/classique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/angelomusa.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/IMG_7779-2-scaled.jpg\",\"datePublished\":\"2024-12-13T16:54:29+00:00\",\"dateModified\":\"2025-10-24T09:32:01+00:00\",\"description\":\"Composez votre bo\u00eete id\u00e9ale avec trois pots de confitures au choix. Parfaite pour offrir ou se faire plaisir, elle allie \u00e9l\u00e9gance et gourmandise, mettant en lumi\u00e8re le savoir-faire artisanal de La Confiture Angelo Musa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angelomusa.com\\\/produit\\\/classique\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angelomusa.com\\\/produit\\\/classique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/angelomusa.com\\\/produit\\\/classique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/angelomusa.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/IMG_7779-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/angelomusa.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/IMG_7779-2-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"A offrir ou \u00e0 savourer le coffret classique Angelo Musa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angelomusa.com\\\/produit\\\/classique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/angelomusa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Boutique\",\"item\":\"https:\\\/\\\/www.angelomusa.com\\\/la-boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Coffret Confiture Classique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.angelomusa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.angelomusa.com\\\/\",\"name\":\"Angelo Musa\",\"description\":\"L\u2019art de la p\u00e2tisserie sublim\u00e9e par un Meilleur Ouvrier de France\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.angelomusa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.angelomusa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.angelomusa.com\\\/#organization\",\"name\":\"Angelo Musa\",\"url\":\"https:\\\/\\\/www.angelomusa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.angelomusa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angelomusa.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/ANGELO-MUSA-ICONE-4.png\",\"contentUrl\":\"https:\\\/\\\/angelomusa.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/ANGELO-MUSA-ICONE-4.png\",\"width\":500,\"height\":500,\"caption\":\"Angelo Musa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.angelomusa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coffret Confiture Classique - Angelo Musa","description":"Composez votre bo\u00eete id\u00e9ale avec trois pots de confitures au choix. Parfaite pour offrir ou se faire plaisir, elle allie \u00e9l\u00e9gance et gourmandise, mettant en lumi\u00e8re le savoir-faire artisanal de La Confiture Angelo Musa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angelomusa.com\/en\/product\/classique\/","og_locale":"en_US","og_type":"article","og_title":"Coffret Confiture Classique - Angelo Musa","og_description":"Composez votre bo\u00eete id\u00e9ale avec trois pots de confitures au choix. Parfaite pour offrir ou se faire plaisir, elle allie \u00e9l\u00e9gance et gourmandise, mettant en lumi\u00e8re le savoir-faire artisanal de La Confiture Angelo Musa.","og_url":"https:\/\/angelomusa.com\/en\/product\/classique\/","og_site_name":"Angelo Musa","article_modified_time":"2025-10-24T09:32:01+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/angelomusa.com\/wp-content\/uploads\/2024\/12\/IMG_7779-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/angelomusa.com\/produit\/classique\/","url":"https:\/\/angelomusa.com\/produit\/classique\/","name":"Coffret Confiture Classique - Angelo Musa","isPartOf":{"@id":"https:\/\/www.angelomusa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/angelomusa.com\/produit\/classique\/#primaryimage"},"image":{"@id":"https:\/\/angelomusa.com\/produit\/classique\/#primaryimage"},"thumbnailUrl":"https:\/\/angelomusa.com\/wp-content\/uploads\/2024\/12\/IMG_7779-2-scaled.jpg","datePublished":"2024-12-13T16:54:29+00:00","dateModified":"2025-10-24T09:32:01+00:00","description":"Composez votre bo\u00eete id\u00e9ale avec trois pots de confitures au choix. Parfaite pour offrir ou se faire plaisir, elle allie \u00e9l\u00e9gance et gourmandise, mettant en lumi\u00e8re le savoir-faire artisanal de La Confiture Angelo Musa.","breadcrumb":{"@id":"https:\/\/angelomusa.com\/produit\/classique\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angelomusa.com\/produit\/classique\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/angelomusa.com\/produit\/classique\/#primaryimage","url":"https:\/\/angelomusa.com\/wp-content\/uploads\/2024\/12\/IMG_7779-2-scaled.jpg","contentUrl":"https:\/\/angelomusa.com\/wp-content\/uploads\/2024\/12\/IMG_7779-2-scaled.jpg","width":1920,"height":2560,"caption":"A offrir ou \u00e0 savourer le coffret classique Angelo Musa"},{"@type":"BreadcrumbList","@id":"https:\/\/angelomusa.com\/produit\/classique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/angelomusa.com\/"},{"@type":"ListItem","position":2,"name":"La Boutique","item":"https:\/\/www.angelomusa.com\/la-boutique\/"},{"@type":"ListItem","position":3,"name":"Coffret Confiture Classique"}]},{"@type":"WebSite","@id":"https:\/\/www.angelomusa.com\/#website","url":"https:\/\/www.angelomusa.com\/","name":"Angelo Musa","description":"L\u2019art de la p\u00e2tisserie sublim\u00e9e par un Meilleur Ouvrier de France","publisher":{"@id":"https:\/\/www.angelomusa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.angelomusa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.angelomusa.com\/#organization","name":"Angelo Musa","url":"https:\/\/www.angelomusa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.angelomusa.com\/#\/schema\/logo\/image\/","url":"https:\/\/angelomusa.com\/wp-content\/uploads\/2024\/11\/ANGELO-MUSA-ICONE-4.png","contentUrl":"https:\/\/angelomusa.com\/wp-content\/uploads\/2024\/11\/ANGELO-MUSA-ICONE-4.png","width":500,"height":500,"caption":"Angelo Musa"},"image":{"@id":"https:\/\/www.angelomusa.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/angelomusa.com\/en\/wp-json\/wp\/v2\/product\/5320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angelomusa.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/angelomusa.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/angelomusa.com\/en\/wp-json\/wp\/v2\/comments?post=5320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/angelomusa.com\/en\/wp-json\/wp\/v2\/media\/5328"}],"wp:attachment":[{"href":"https:\/\/angelomusa.com\/en\/wp-json\/wp\/v2\/media?parent=5320"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/angelomusa.com\/en\/wp-json\/wp\/v2\/product_brand?post=5320"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/angelomusa.com\/en\/wp-json\/wp\/v2\/product_cat?post=5320"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/angelomusa.com\/en\/wp-json\/wp\/v2\/product_tag?post=5320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}